{"id":29376,"date":"2026-04-02T10:23:28","date_gmt":"2026-04-02T13:23:28","guid":{"rendered":"https:\/\/confirp.com.br\/?page_id=29376"},"modified":"2026-05-05T13:37:18","modified_gmt":"2026-05-05T16:37:18","slug":"multinacionais","status":"publish","type":"page","link":"https:\/\/confirp.com.br\/en\/multinacionais\/","title":{"rendered":"Multinacionais"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29376\" class=\"elementor elementor-29376\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1db5013 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"1db5013\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f8efe91 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"f8efe91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e190057 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"e190057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">MULTINACIONAIS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-779dcd0 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"779dcd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, controle e padr\u00e3o global<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f37b63 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2f37b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A Confirp estrutura, implementa e gerencia a opera\u00e7\u00e3o de empresas multinacionais no Brasil com compliance, intelig\u00eancia financeira e integra\u00e7\u00e3o com a matriz.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb6758e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fb6758e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Atuamos desde a entrada no pa\u00eds at\u00e9 a gest\u00e3o cont\u00ednua da opera\u00e7\u00e3o, garantindo efici\u00eancia, redu\u00e7\u00e3o de riscos e total alinhamento com padr\u00f5es internacionais.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a5cc46 elementor-widget elementor-widget-button\" data-id=\"0a5cc46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fale com um especialista<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-debb05c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"debb05c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7ebc051 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"7ebc051\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e429719 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e429719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fale conosco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd9cf8 elementor-widget elementor-widget-text-editor\" data-id=\"fbd9cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nossa equipe entrar\u00e1 em contato para entender sua opera\u00e7\u00e3o e orientar a melhor estrutura para atua\u00e7\u00e3o no Brasil.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c946494 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"c946494\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Pr\\u00f3ximo&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"formulario_multionacional\" name=\"Formul\u00e1rio Multinacional\" aria-label=\"Formul\u00e1rio Multinacional\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"29376\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c946494\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"29376\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-telefone elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telefone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[telefone]\" id=\"form-field-telefone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefone\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-pais elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-pais\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPa\u00eds de origem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[pais]\" id=\"form-field-pais\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pa\u00eds de origem\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-mensagem elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-mensagem\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[mensagem]\" id=\"form-field-mensagem\" rows=\"4\" placeholder=\"Mensagem\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[antispam]\" id=\"form-field-antispam\" class=\"elementor-field elementor-size-sm \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-recaptcha elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-recaptcha\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LeLjBUiAAAAAFZzCszxl3WRxvbU_CdefKbK-tR7\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\" id=\"botao_tributario\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Falar com especialista agora via WhatsApp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66194e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"66194e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13ee42d\" data-id=\"13ee42d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2233cf8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2233cf8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-320295e\" data-id=\"320295e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c70eb7f elementor-widget elementor-widget-heading\" data-id=\"c70eb7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Sua empresa est\u00e1 expandindo para o Brasil? N\u00f3s cuidamos da estrutura.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612d181 elementor-widget elementor-widget-text-editor\" data-id=\"612d181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A Confirp atende empresas internacionais que precisam operar com seguran\u00e7a e previsibilidade no ambiente brasileiro.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-03a2c6c\" data-id=\"03a2c6c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f04440b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f04440b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Perfis atendidos<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Empresas entrando no Brasil pela primeira vez<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Multinacionais que j\u00e1 operam no pa\u00eds e precisam de mais controle<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Empresas que precisam integrar opera\u00e7\u00e3o local com matriz global<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Organiza\u00e7\u00f5es que buscam reduzir riscos fiscais e trabalhistas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8f19446 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"8f19446\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d41a2f8 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d41a2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Expandir para o Brasil sem estrutura pode gerar riscos e custos elevados\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb5e6b elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3fb5e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Complexidade tribut\u00e1ria e alto risco fiscal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Legisla\u00e7\u00e3o trabalhista rigorosa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mudan\u00e7as frequentes na regulamenta\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Falta de integra\u00e7\u00e3o com padr\u00f5es globais (IFRS \/ US GAAP)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Baixa visibilidade financeira da opera\u00e7\u00e3o local<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Risco de passivos e conting\u00eancias<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65cfe5b elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"65cfe5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Fale com um especialista Confirp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02281a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"02281a1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e73b014\" data-id=\"e73b014\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a202d9 elementor-widget elementor-widget-heading\" data-id=\"9a202d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Uma estrutura completa para sua opera\u00e7\u00e3o no Brasil\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f35ba37 elementor-widget elementor-widget-ucaddon_timeline_bullets\" data-id=\"f35ba37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_timeline_bullets.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Timeline Bullets -->\n\t\t<link id='font-awesome-css' href='https:\/\/confirp.com.br\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/confirp.com.br\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Timeline Bullets *\/\n\n\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item{\n  display:flex;\n  position:relative;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_icon{ \n  display:flex;\n  align-items:center;\n  justify-content:center;\n  flex-grow:0;\n  flex-shrink:0;\n  line-height:1em;\n  overflow:hidden;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_icon img{\n  object-fit: cover;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_icon svg{ \n  height:1em;\n  width:1em;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_spacer{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_hr_line{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_vr_line{\n  height:100%;\n  position:absolute;\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_title, \n#uc_timeline_bullets_elementor_f35ba37 .ue_item_text,\n#uc_timeline_bullets_elementor_f35ba37 .ue_item_icon{\n  transition: all .3s ease-out;\n}\n\n.ue_item_title{\n  font-size:21px;\n}\n\n#uc_timeline_bullets_elementor_f35ba37.uc-remote-parent .ue_item{\n  cursor:pointer;\n}\n\n<\/style>\n\n<div id=\"uc_timeline_bullets_elementor_f35ba37\" class=\"uc-items-wrapper  \"   role=\"list\">\n  <div class=\"ue_item elementor-repeater-item-10b9b9d\" role=\"listitem\" tabindex=\"0\">\n  <div class=\"ue_item_vr_line\"><\/div>\n  <div class=\"ue_item_hr_line\"><\/div>\n  <div class=\"ue_item_icon\">\n    <i class='fas fa-globe-americas'><\/i>          <\/div>\n  <div class=\"ue_item_spacer\"><\/div>\n  <div class=\"ue_item_content\">\n    <div class=\"ue_item_title\">Brazil Market Entry<\/div>    <div class=\"ue_item_text\">Abertura de empresa, estrutura societ\u00e1ria e planejamento tribut\u00e1rio\n<\/div>  <\/div>\n<\/div>\n<div class=\"ue_item elementor-repeater-item-c5f5872\" role=\"listitem\" tabindex=\"0\">\n  <div class=\"ue_item_vr_line\"><\/div>\n  <div class=\"ue_item_hr_line\"><\/div>\n  <div class=\"ue_item_icon\">\n    <i class='fas fa-shield-alt'><\/i>          <\/div>\n  <div class=\"ue_item_spacer\"><\/div>\n  <div class=\"ue_item_content\">\n    <div class=\"ue_item_title\">Compliance e Gest\u00e3o de Riscos<\/div>    <div class=\"ue_item_text\">Gest\u00e3o fiscal, cont\u00e1bil e trabalhista com redu\u00e7\u00e3o de riscos\n<\/div>  <\/div>\n<\/div>\n<div class=\"ue_item elementor-repeater-item-6b69aa9\" role=\"listitem\" tabindex=\"0\">\n  <div class=\"ue_item_vr_line\"><\/div>\n  <div class=\"ue_item_hr_line\"><\/div>\n  <div class=\"ue_item_icon\">\n    <i class='fas fa-chart-line'><\/i>          <\/div>\n  <div class=\"ue_item_spacer\"><\/div>\n  <div class=\"ue_item_content\">\n    <div class=\"ue_item_title\">Intelig\u00eancia Financeira<\/div>    <div class=\"ue_item_text\">Relat\u00f3rios, dashboards e apoio estrat\u00e9gico para decis\u00f5es\n<\/div>  <\/div>\n<\/div>\n<div class=\"ue_item elementor-repeater-item-590c20a\" role=\"listitem\" tabindex=\"0\">\n  <div class=\"ue_item_vr_line\"><\/div>\n  <div class=\"ue_item_hr_line\"><\/div>\n  <div class=\"ue_item_icon\">\n    <i class='fas fa-share-alt'><\/i>          <\/div>\n  <div class=\"ue_item_spacer\"><\/div>\n  <div class=\"ue_item_content\">\n    <div class=\"ue_item_title\">Integra\u00e7\u00e3o com a Matriz<\/div>    <div class=\"ue_item_text\">Padroniza\u00e7\u00e3o internacional, ERP e consolida\u00e7\u00e3o de informa\u00e7\u00f5es\n<\/div>  <\/div>\n<\/div>\n\n<\/div>\n<!-- end Timeline Bullets -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-eba404f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"eba404f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eef5419 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"eef5419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Por que escolher a Confirp para sua opera\u00e7\u00e3o no Brasil\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b070df6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"b070df6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c57d4cf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"c57d4cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa46d22 elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fa46d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Especializa\u00e7\u00e3o no ambiente brasileiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d38afb elementor-widget elementor-widget-text-editor\" data-id=\"4d38afb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Conhecimento profundo da legisla\u00e7\u00e3o e do sistema tribut\u00e1rio<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9b1d9c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b9b1d9c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbbf934 elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cbbf934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Atendimento preparado para multinacionais<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f74fb9 elementor-widget elementor-widget-text-editor\" data-id=\"9f74fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Comunica\u00e7\u00e3o estruturada e alinhada com times globais<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-965489d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"965489d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca76534 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"ca76534\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44d36a9 elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"44d36a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tecnologia e efici\u00eancia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61ea4a2 elementor-widget elementor-widget-text-editor\" data-id=\"61ea4a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Processos integrados, dashboards e automa\u00e7\u00e3o<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f31a7c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"7f31a7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4911d5a elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4911d5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hub especializado (Equity + Global)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e392fea elementor-widget elementor-widget-text-editor\" data-id=\"e392fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Estrutura dedicada para opera\u00e7\u00f5es internacionais<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-942571d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"942571d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ab5fa92 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"ab5fa92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f85c794 elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f85c794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" x=\"0\" y=\"0\" viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon\"><path d=\"m55 24v14s-1 12-15 16a28.005 28.005 0 0 1 -24-4s34 10 39-26z\" fill=\"#f7f7f7\" data-original=\"#e1edff\" class=\"\"><\/path><g fill=\"#4c5dff\"><path d=\"m36 10a18.021 18.021 0 0 1 18 18v8a18.021 18.021 0 0 1 -18 18h-8a18.021 18.021 0 0 1 -18-18v-8a18.021 18.021 0 0 1 18-18zm0-2h-8a20 20 0 0 0 -20 20v8a20 20 0 0 0 20 20h8a20 20 0 0 0 20-20v-8a20 20 0 0 0 -20-20z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><path d=\"m42.707 32.707-12 12a1 1 0 0 1 -1.414-1.414l11.293-11.293-11.293-11.293a1 1 0 0 1 1.414-1.414l12 12a1 1 0 0 1 0 1.414zm-8-1.414-12-12a1 1 0 0 0 -1.414 1.414l11.293 11.293-11.293 11.293a1 1 0 1 0 1.414 1.414l12-12a1 1 0 0 0 0-1.414z\" fill=\"#0042c5\" data-original=\"#4c5dff\" class=\"\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seguran\u00e7a e confidencialidade<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-659759b elementor-widget elementor-widget-text-editor\" data-id=\"659759b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Prote\u00e7\u00e3o total das informa\u00e7\u00f5es e governan\u00e7a<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2711acc e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"2711acc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b25170d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b25170d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44ffc85 elementor-widget elementor-widget-heading\" data-id=\"44ffc85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empresas que operam com seguran\u00e7a no Brasil contam com a Confirp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33bc90c elementor-widget elementor-widget-text-editor\" data-id=\"33bc90c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Atendemos empresas nacionais e multinacionais que precisam de controle, previsibilidade e conformidade em suas opera\u00e7\u00f5es.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0faa35e elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"0faa35e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_tablet&quot;:&quot;6&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/APPLUS-IDIADA.png\" alt=\"APPLUS IDIADA\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/FERRAGAMO.png\" alt=\"FERRAGAMO\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/INFOSYS.png\" alt=\"INFOSYS\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/JAS.png\" alt=\"JAS\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/LAPP.png\" alt=\"LAPP\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2026\/04\/TUBACEX-GROUP.png\" alt=\"TUBACEX GROUP\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c78fdd1 elementor-widget elementor-widget-heading\" data-id=\"c78fdd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Depoimento Frederico Messina<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3f02bf elementor-widget elementor-widget-text-editor\" data-id=\"c3f02bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gerente financeiro na Am\u00e9rica do Sul da Ferragamo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53bfdd8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"53bfdd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d96cafb elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-video\" data-id=\"d96cafb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=uKTTR4SD69I&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-776a63c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"776a63c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f39ec8d\" data-id=\"f39ec8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff43770 elementor-widget elementor-widget-heading\" data-id=\"ff43770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pronto para estruturar sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb47884 elementor-widget elementor-widget-text-editor\" data-id=\"fb47884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Fale com um especialista da Confirp e entenda como iniciar ou otimizar sua atua\u00e7\u00e3o no pa\u00eds.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e07abe6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e07abe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar conversa estrat\u00e9gica<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d50782 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4d50782\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e4714e\" data-id=\"3e4714e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04b99bc elementor-widget elementor-widget-heading\" data-id=\"04b99bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perguntas Frequentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e26befb elementor-widget elementor-widget-accordion\" data-id=\"e26befb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2371\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2371\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">A Confirp atende empresas que ainda n\u00e3o possuem opera\u00e7\u00e3o no Brasil?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2371\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2371\"><p><span style=\"font-weight: 400;\">Sim. Atuamos desde a estrutura\u00e7\u00e3o inicial at\u00e9 a opera\u00e7\u00e3o completa da empresa no pa\u00eds.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2372\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2372\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">A Confirp integra a opera\u00e7\u00e3o com sistemas globais?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2372\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2372\"><p><span style=\"font-weight: 400;\">Sim. Trabalhamos com integra\u00e7\u00e3o a ERPs e adapta\u00e7\u00e3o a padr\u00f5es internacionais como IFRS e US GAAP.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2373\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2373\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">A Confirp cuida de toda a parte fiscal e trabalhista?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2373\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2373\"><p><span style=\"font-weight: 400;\">Sim. Gerenciamos toda a opera\u00e7\u00e3o cont\u00e1bil, fiscal e trabalhista da empresa no Brasil.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2374\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2374\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">A Confirp apoia a expans\u00e3o da opera\u00e7\u00e3o no pa\u00eds?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2374\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2374\"><p><span style=\"font-weight: 400;\">Sim. Al\u00e9m da estrutura inicial, acompanhamos o crescimento com intelig\u00eancia financeira e suporte estrat\u00e9gico.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"A Confirp atende empresas que ainda n\\u00e3o possuem opera\\u00e7\\u00e3o no Brasil?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sim. Atuamos desde a estrutura\\u00e7\\u00e3o inicial at\\u00e9 a opera\\u00e7\\u00e3o completa da empresa no pa\\u00eds.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"A Confirp integra a opera\\u00e7\\u00e3o com sistemas globais?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sim. Trabalhamos com integra\\u00e7\\u00e3o a ERPs e adapta\\u00e7\\u00e3o a padr\\u00f5es internacionais como IFRS e US GAAP.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"A Confirp cuida de toda a parte fiscal e trabalhista?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sim. Gerenciamos toda a opera\\u00e7\\u00e3o cont\\u00e1bil, fiscal e trabalhista da empresa no Brasil.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"A Confirp apoia a expans\\u00e3o da opera\\u00e7\\u00e3o no pa\\u00eds?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sim. Al\\u00e9m da estrutura inicial, acompanhamos o crescimento com intelig\\u00eancia financeira e suporte estrat\\u00e9gico.<\\\/span><\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MULTINACIONAIS Sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, controle e padr\u00e3o global A Confirp estrutura, implementa e gerencia a opera\u00e7\u00e3o de empresas multinacionais no Brasil com compliance, intelig\u00eancia financeira e integra\u00e7\u00e3o com a matriz. Atuamos desde a entrada no pa\u00eds at\u00e9 a gest\u00e3o cont\u00ednua da opera\u00e7\u00e3o, garantindo efici\u00eancia, redu\u00e7\u00e3o de riscos e total alinhamento com padr\u00f5es internacionais. Fale com um especialista Fale conosco Nossa equipe entrar\u00e1 em contato para entender sua opera\u00e7\u00e3o e orientar a melhor estrutura para atua\u00e7\u00e3o no Brasil. Sua empresa est\u00e1 expandindo para o Brasil? N\u00f3s cuidamos da estrutura. A Confirp atende empresas internacionais que precisam operar com seguran\u00e7a e previsibilidade no ambiente brasileiro. Perfis atendidos Empresas entrando no Brasil pela primeira vez Multinacionais que j\u00e1 operam no pa\u00eds e precisam de mais controle Empresas que precisam integrar opera\u00e7\u00e3o local com matriz global Organiza\u00e7\u00f5es que buscam reduzir riscos fiscais e trabalhistas Expandir para o Brasil sem estrutura pode gerar riscos e custos elevados Complexidade tribut\u00e1ria e alto risco fiscal Legisla\u00e7\u00e3o trabalhista rigorosa Mudan\u00e7as frequentes na regulamenta\u00e7\u00e3o Falta de integra\u00e7\u00e3o com padr\u00f5es globais (IFRS \/ US GAAP) Baixa visibilidade financeira da opera\u00e7\u00e3o local Risco de passivos e conting\u00eancias Fale com um especialista Confirp Uma estrutura completa para sua opera\u00e7\u00e3o no Brasil Brazil Market Entry Abertura de empresa, estrutura societ\u00e1ria e planejamento tribut\u00e1rio Compliance e Gest\u00e3o de Riscos Gest\u00e3o fiscal, cont\u00e1bil e trabalhista com redu\u00e7\u00e3o de riscos Intelig\u00eancia Financeira Relat\u00f3rios, dashboards e apoio estrat\u00e9gico para decis\u00f5es Integra\u00e7\u00e3o com a Matriz Padroniza\u00e7\u00e3o internacional, ERP e consolida\u00e7\u00e3o de informa\u00e7\u00f5es Por que escolher a Confirp para sua opera\u00e7\u00e3o no Brasil Especializa\u00e7\u00e3o no ambiente brasileiro Conhecimento profundo da legisla\u00e7\u00e3o e do sistema tribut\u00e1rio Atendimento preparado para multinacionais Comunica\u00e7\u00e3o estruturada e alinhada com times globais Tecnologia e efici\u00eancia Processos integrados, dashboards e automa\u00e7\u00e3o Hub especializado (Equity + Global) Estrutura dedicada para opera\u00e7\u00f5es internacionais Seguran\u00e7a e confidencialidade Prote\u00e7\u00e3o total das informa\u00e7\u00f5es e governan\u00e7a Empresas que operam com seguran\u00e7a no Brasil contam com a Confirp Atendemos empresas nacionais e multinacionais que precisam de controle, previsibilidade e conformidade em suas opera\u00e7\u00f5es. &nbsp; Depoimento Frederico Messina Gerente financeiro na Am\u00e9rica do Sul da Ferragamo. Pronto para estruturar sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a? Fale com um especialista da Confirp e entenda como iniciar ou otimizar sua atua\u00e7\u00e3o no pa\u00eds. Agendar conversa estrat\u00e9gica Perguntas Frequentes A Confirp atende empresas que ainda n\u00e3o possuem opera\u00e7\u00e3o no Brasil? Sim. Atuamos desde a estrutura\u00e7\u00e3o inicial at\u00e9 a opera\u00e7\u00e3o completa da empresa no pa\u00eds. A Confirp integra a opera\u00e7\u00e3o com sistemas globais? Sim. Trabalhamos com integra\u00e7\u00e3o a ERPs e adapta\u00e7\u00e3o a padr\u00f5es internacionais como IFRS e US GAAP. A Confirp cuida de toda a parte fiscal e trabalhista? Sim. Gerenciamos toda a opera\u00e7\u00e3o cont\u00e1bil, fiscal e trabalhista da empresa no Brasil. A Confirp apoia a expans\u00e3o da opera\u00e7\u00e3o no pa\u00eds? Sim. Al\u00e9m da estrutura inicial, acompanhamos o crescimento com intelig\u00eancia financeira e suporte estrat\u00e9gico.<\/p>\n","protected":false},"author":23,"featured_media":21879,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-29376","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o<\/title>\n<meta name=\"description\" content=\"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confirp.com.br\/en\/multinacionais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confirp.com.br\/en\/multinacionais\/\" \/>\n<meta property=\"og:site_name\" content=\"CONFIRP\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T16:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confirp.com.br\/wp-content\/uploads\/2023\/05\/por-que-contratar-um-escritorio-de-contabilidade.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1597\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/\",\"url\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/\",\"name\":\"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confirp.com.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/por-que-contratar-um-escritorio-de-contabilidade.jpg\",\"datePublished\":\"2026-04-02T13:23:28+00:00\",\"dateModified\":\"2026-05-05T16:37:18+00:00\",\"description\":\"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confirp.com.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/por-que-contratar-um-escritorio-de-contabilidade.jpg\",\"contentUrl\":\"https:\\\/\\\/confirp.com.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/por-que-contratar-um-escritorio-de-contabilidade.jpg\",\"width\":1597,\"height\":969,\"caption\":\"por que contratar um escrit\u00f3rio de contabilidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/multinacionais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Multinacionais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/\",\"name\":\"CONFIRP\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#organization\",\"name\":\"CONFIRP\",\"url\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confirp.com.br\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-confirp.svg\",\"contentUrl\":\"https:\\\/\\\/confirp.com.br\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-confirp.svg\",\"width\":176,\"height\":40,\"caption\":\"CONFIRP\"},\"image\":{\"@id\":\"https:\\\/\\\/confirp.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o","description":"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confirp.com.br\/en\/multinacionais\/","og_locale":"en_US","og_type":"article","og_title":"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o","og_description":"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.","og_url":"https:\/\/confirp.com.br\/en\/multinacionais\/","og_site_name":"CONFIRP","article_modified_time":"2026-05-05T16:37:18+00:00","og_image":[{"width":1597,"height":969,"url":"https:\/\/confirp.com.br\/wp-content\/uploads\/2023\/05\/por-que-contratar-um-escritorio-de-contabilidade.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/confirp.com.br\/en\/multinacionais\/","url":"https:\/\/confirp.com.br\/en\/multinacionais\/","name":"Opera\u00e7\u00e3o no Brasil para Multinacionais | Compliance e Gest\u00e3o","isPartOf":{"@id":"https:\/\/confirp.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confirp.com.br\/en\/multinacionais\/#primaryimage"},"image":{"@id":"https:\/\/confirp.com.br\/en\/multinacionais\/#primaryimage"},"thumbnailUrl":"https:\/\/confirp.com.br\/wp-content\/uploads\/2023\/05\/por-que-contratar-um-escritorio-de-contabilidade.jpg","datePublished":"2026-04-02T13:23:28+00:00","dateModified":"2026-05-05T16:37:18+00:00","description":"Estruture e gerencie sua opera\u00e7\u00e3o no Brasil com seguran\u00e7a, compliance e padr\u00e3o global. Solu\u00e7\u00f5es completas para multinacionais com efici\u00eancia.","breadcrumb":{"@id":"https:\/\/confirp.com.br\/en\/multinacionais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confirp.com.br\/en\/multinacionais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/confirp.com.br\/en\/multinacionais\/#primaryimage","url":"https:\/\/confirp.com.br\/wp-content\/uploads\/2023\/05\/por-que-contratar-um-escritorio-de-contabilidade.jpg","contentUrl":"https:\/\/confirp.com.br\/wp-content\/uploads\/2023\/05\/por-que-contratar-um-escritorio-de-contabilidade.jpg","width":1597,"height":969,"caption":"por que contratar um escrit\u00f3rio de contabilidade"},{"@type":"BreadcrumbList","@id":"https:\/\/confirp.com.br\/en\/multinacionais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/confirp.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Multinacionais"}]},{"@type":"WebSite","@id":"https:\/\/confirp.com.br\/en\/#website","url":"https:\/\/confirp.com.br\/en\/","name":"CONFIRP","description":"","publisher":{"@id":"https:\/\/confirp.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confirp.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/confirp.com.br\/en\/#organization","name":"CONFIRP","url":"https:\/\/confirp.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/confirp.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/confirp.com.br\/wp-content\/uploads\/2018\/09\/logo-confirp.svg","contentUrl":"https:\/\/confirp.com.br\/wp-content\/uploads\/2018\/09\/logo-confirp.svg","width":176,"height":40,"caption":"CONFIRP"},"image":{"@id":"https:\/\/confirp.com.br\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/pages\/29376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/comments?post=29376"}],"version-history":[{"count":0,"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/pages\/29376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/media\/21879"}],"wp:attachment":[{"href":"https:\/\/confirp.com.br\/en\/wp-json\/wp\/v2\/media?parent=29376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}